{"id":188957,"date":"2025-12-26T12:46:39","date_gmt":"2025-12-26T09:46:39","guid":{"rendered":"http:\/\/wardoon.net\/so\/?p=188957"},"modified":"2025-12-26T12:46:39","modified_gmt":"2025-12-26T09:46:39","slug":"daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay","status":"publish","type":"post","link":"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/","title":{"rendered":"DAAWO: Tirinta codadka doorashadii ka dhacday Muqdisho oo bilaabatay"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-188934\" src=\"http:\/\/wardoon.net\/so\/wp-content\/uploads\/2025\/12\/Screenshot_20251225-095751_Facebook-696x387-1.jpg\" alt=\"\" width=\"696\" height=\"387\" srcset=\"https:\/\/wardoon.net\/so\/wp-content\/uploads\/2025\/12\/Screenshot_20251225-095751_Facebook-696x387-1.jpg 696w, https:\/\/wardoon.net\/so\/wp-content\/uploads\/2025\/12\/Screenshot_20251225-095751_Facebook-696x387-1-300x167.jpg 300w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/p>\n<p>Waxaa si habsami leh u socota tirinta codadka doorashadii goleyaasha degaanka gobolka Banaadir ee shalay ka dhacday magaalada Muqdisho taasoo ay ku loolamayeen illaa 20 xisbi siyaasadeed.<\/p>\n<p>Inkastoo aysan jirin illaa hadda natiijooyin hordhac ah oo ay soo saareen guddiga doorashooyinka qaranka ayaa haddana codadka illaa hadda la tiriyey waxay warar xog ogaal ahi sheegayaan iney ku horeeyaan xisbiyada JSP ee uu hogaamiyo madaxweyne Xassan Shiikh iyo Xisbiga Ramaas.<\/p>\n<p>Waxaa sidoo kale codad badan oo aan la dhayalsan Karin helay xisbiyo kale oo tartanka ku jiray, iyadoo natiijada kama dambeysta ah la filayo iney ku dhawaaqaan guddiga doorashooyinka maalmaha soo socda.<\/p>\n<p>Xaalada magaalada Muqdisho ayaa xalay illaa saaka caadi ku soo laabatay, iyadoo ay dib u bilowdeen socodka noocyada kala duwan ee gaadiidka dadweynaha oo shalay loo hakiyey doorashooyinka magaalada ka jiray.<\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=314&amp;href=https%3A%2F%2Fwww.facebook.com%2Freel%2F1416087136780881%2F&amp;show_text=false&amp;width=560&amp;t=0\" width=\"560\" height=\"314\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Waxaa si habsami leh u socota tirinta codadka doorashadii goleyaasha degaanka gobolka Banaadir ee shalay ka dhacday magaalada Muqdisho taasoo ay ku loolamayeen illaa 20 xisbi siyaasadeed. Inkastoo aysan jirin illaa hadda natiijooyin hordhac ah oo ay soo saareen guddiga doorashooyinka qaranka ayaa haddana codadka illaa hadda la tiriyey waxay warar xog ogaal ahi sheegayaan [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":188934,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"no","rop_publish_now_accounts":{"facebook_10221280388112155_325455220908133":""},"rop_publish_now_history":[{"account":"facebook_10221280388112155_325455220908133","service":"facebook","timestamp":1766742445,"status":"success"}],"rop_publish_now_status":"done","footnotes":""},"categories":[3],"tags":[],"class_list":["post-188957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-somali-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DAAWO: Tirinta codadka doorashadii ka dhacday Muqdisho oo bilaabatay - Wardoon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DAAWO: Tirinta codadka doorashadii ka dhacday Muqdisho oo bilaabatay - Wardoon\" \/>\n<meta property=\"og:description\" content=\"Waxaa si habsami leh u socota tirinta codadka doorashadii goleyaasha degaanka gobolka Banaadir ee shalay ka dhacday magaalada Muqdisho taasoo ay ku loolamayeen illaa 20 xisbi siyaasadeed. Inkastoo aysan jirin illaa hadda natiijooyin hordhac ah oo ay soo saareen guddiga doorashooyinka qaranka ayaa haddana codadka illaa hadda la tiriyey waxay warar xog ogaal ahi sheegayaan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/\" \/>\n<meta property=\"og:site_name\" content=\"Wardoon\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-26T09:46:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wardoon.net\/so\/wp-content\/uploads\/2025\/12\/Screenshot_20251225-095751_Facebook-696x387-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"387\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/\",\"url\":\"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/\",\"name\":\"DAAWO: Tirinta codadka doorashadii ka dhacday Muqdisho oo bilaabatay - Wardoon\",\"isPartOf\":{\"@id\":\"http:\/\/wardoon.net\/so\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/wardoon.net\/so\/wp-content\/uploads\/2025\/12\/Screenshot_20251225-095751_Facebook-696x387-1.jpg\",\"datePublished\":\"2025-12-26T09:46:39+00:00\",\"author\":{\"@id\":\"http:\/\/wardoon.net\/so\/#\/schema\/person\/f8b1d5296096e3c329f5b915ba044a28\"},\"breadcrumb\":{\"@id\":\"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/#primaryimage\",\"url\":\"https:\/\/wardoon.net\/so\/wp-content\/uploads\/2025\/12\/Screenshot_20251225-095751_Facebook-696x387-1.jpg\",\"contentUrl\":\"https:\/\/wardoon.net\/so\/wp-content\/uploads\/2025\/12\/Screenshot_20251225-095751_Facebook-696x387-1.jpg\",\"width\":696,\"height\":387},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/wardoon.net\/so\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DAAWO: Tirinta codadka doorashadii ka dhacday Muqdisho oo bilaabatay\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/wardoon.net\/so\/#website\",\"url\":\"http:\/\/wardoon.net\/so\/\",\"name\":\"Wardoon\",\"description\":\"News Media\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/wardoon.net\/so\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/wardoon.net\/so\/#\/schema\/person\/f8b1d5296096e3c329f5b915ba044a28\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/wardoon.net\/so\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/23bb9e404592c76192c930b0cfbf0010?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/23bb9e404592c76192c930b0cfbf0010?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/wardoon.net\/so\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DAAWO: Tirinta codadka doorashadii ka dhacday Muqdisho oo bilaabatay - Wardoon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/","og_locale":"en_US","og_type":"article","og_title":"DAAWO: Tirinta codadka doorashadii ka dhacday Muqdisho oo bilaabatay - Wardoon","og_description":"Waxaa si habsami leh u socota tirinta codadka doorashadii goleyaasha degaanka gobolka Banaadir ee shalay ka dhacday magaalada Muqdisho taasoo ay ku loolamayeen illaa 20 xisbi siyaasadeed. Inkastoo aysan jirin illaa hadda natiijooyin hordhac ah oo ay soo saareen guddiga doorashooyinka qaranka ayaa haddana codadka illaa hadda la tiriyey waxay warar xog ogaal ahi sheegayaan [&hellip;]","og_url":"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/","og_site_name":"Wardoon","article_published_time":"2025-12-26T09:46:39+00:00","og_image":[{"width":696,"height":387,"url":"https:\/\/wardoon.net\/so\/wp-content\/uploads\/2025\/12\/Screenshot_20251225-095751_Facebook-696x387-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/","url":"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/","name":"DAAWO: Tirinta codadka doorashadii ka dhacday Muqdisho oo bilaabatay - Wardoon","isPartOf":{"@id":"http:\/\/wardoon.net\/so\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/#primaryimage"},"image":{"@id":"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/#primaryimage"},"thumbnailUrl":"https:\/\/wardoon.net\/so\/wp-content\/uploads\/2025\/12\/Screenshot_20251225-095751_Facebook-696x387-1.jpg","datePublished":"2025-12-26T09:46:39+00:00","author":{"@id":"http:\/\/wardoon.net\/so\/#\/schema\/person\/f8b1d5296096e3c329f5b915ba044a28"},"breadcrumb":{"@id":"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/#primaryimage","url":"https:\/\/wardoon.net\/so\/wp-content\/uploads\/2025\/12\/Screenshot_20251225-095751_Facebook-696x387-1.jpg","contentUrl":"https:\/\/wardoon.net\/so\/wp-content\/uploads\/2025\/12\/Screenshot_20251225-095751_Facebook-696x387-1.jpg","width":696,"height":387},{"@type":"BreadcrumbList","@id":"https:\/\/wardoon.net\/so\/daawo-tirinta-codadka-doorashadii-ka-dhacday-muqdisho-oo-bilaabatay\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/wardoon.net\/so\/"},{"@type":"ListItem","position":2,"name":"DAAWO: Tirinta codadka doorashadii ka dhacday Muqdisho oo bilaabatay"}]},{"@type":"WebSite","@id":"http:\/\/wardoon.net\/so\/#website","url":"http:\/\/wardoon.net\/so\/","name":"Wardoon","description":"News Media","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/wardoon.net\/so\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"http:\/\/wardoon.net\/so\/#\/schema\/person\/f8b1d5296096e3c329f5b915ba044a28","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/wardoon.net\/so\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/23bb9e404592c76192c930b0cfbf0010?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23bb9e404592c76192c930b0cfbf0010?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/wardoon.net\/so\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/wardoon.net\/so\/wp-json\/wp\/v2\/posts\/188957"}],"collection":[{"href":"https:\/\/wardoon.net\/so\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wardoon.net\/so\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wardoon.net\/so\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wardoon.net\/so\/wp-json\/wp\/v2\/comments?post=188957"}],"version-history":[{"count":1,"href":"https:\/\/wardoon.net\/so\/wp-json\/wp\/v2\/posts\/188957\/revisions"}],"predecessor-version":[{"id":188958,"href":"https:\/\/wardoon.net\/so\/wp-json\/wp\/v2\/posts\/188957\/revisions\/188958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wardoon.net\/so\/wp-json\/wp\/v2\/media\/188934"}],"wp:attachment":[{"href":"https:\/\/wardoon.net\/so\/wp-json\/wp\/v2\/media?parent=188957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wardoon.net\/so\/wp-json\/wp\/v2\/categories?post=188957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wardoon.net\/so\/wp-json\/wp\/v2\/tags?post=188957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}